{"id":3202,"date":"2023-06-09T12:16:23","date_gmt":"2023-06-09T10:16:23","guid":{"rendered":"https:\/\/www.snamiroma.org\/wp1\/?p=3202"},"modified":"2023-06-09T12:16:27","modified_gmt":"2023-06-09T10:16:27","slug":"nuovo-piano-terapeutico-aifa-per-acido-bempedoico","status":"publish","type":"post","link":"https:\/\/www.snamiroma.org\/wp1\/2023\/06\/09\/nuovo-piano-terapeutico-aifa-per-acido-bempedoico\/","title":{"rendered":"Nuovo piano terapeutico AIFA per acido BEMPEDOICO"},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><em>Quo usque tandem<\/em>\u2026 <strong>Attoniti veniamo investiti dell\u2019ennesimo piano terapeutico,<\/strong> questa volta cartaceo, per la prescrizione di farmaci a base di <strong><span style=\"text-decoration: underline;\">acido bempedoico<\/span><\/strong>. Mentre ogni giorno ascoltiamo dai decisori promesse di riduzione della burocrazia per il MMG, l\u2019AIFA introduce questo nuovo piano terapeutico. Ormai puntuale come la notte che segue il giorno arrivano con cadenza poco pi\u00f9 che settimanale, <strong>nuovi piani terapeutici per farmaci, presidi, nuove certificazioni, nuovi indicatori di appropriatezza prescrittiva e nuove note.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-style-plain has-black-color has-white-background-color has-text-color has-background is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">&#8220;Noi MMG ci mettiamo <strong>tutto l\u2019impegno possibile per essere appropriati <\/strong>e riteniamo nostro compito fondamentale assicurare al nostro paziente le migliori cure nel rispetto delle linee guida e delle evidenze scientifiche, ma riteniamo la<strong> <\/strong><span style=\"text-decoration: underline;\"><strong>parte burocratica e le inappropriatezze di tutto il sistema della prescrizione ormai => insostenibile<\/strong><\/span>&#8220;<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Documenti allegati:<\/h3>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/SNAMI_Roma_comunicazione_Acido_bempedoico_v002.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di SNAMI_Roma_comunicazione_Acido_bempedoico_v002.\"><\/object><a id=\"wp-block-file--media-b7fc236a-d9e9-422a-ac55-a295bd345f2b\" href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/SNAMI_Roma_comunicazione_Acido_bempedoico_v002.pdf\">SNAMI_Roma_comunicazione_Acido_bempedoico_v002<\/a><a href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/SNAMI_Roma_comunicazione_Acido_bempedoico_v002.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-b7fc236a-d9e9-422a-ac55-a295bd345f2b\">Download<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/piano-terapeutico-ac-bempedoico_v001.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di piano-terapeutico-ac-bempedoico_v001.\"><\/object><a id=\"wp-block-file--media-30d57912-8326-4b51-8289-19c440ab9ce7\" href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/piano-terapeutico-ac-bempedoico_v001.pdf\">piano-terapeutico-ac-bempedoico_v001<\/a><a href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2023\/06\/piano-terapeutico-ac-bempedoico_v001.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-30d57912-8326-4b51-8289-19c440ab9ce7\">Download<\/a><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 has-author wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/07\/26\/in-memoriam-dott-giuseppe-di-donna\/\">IN MEMORIAM: Dott. Giuseppe Di Donna<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">In Memoriam | Oggi apprendiamo della perdita del nostro amato amico e collega, Giuseppe&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/07\/07\/tar-lazio-sentenza-n-11984-2026-illegittima-la-prescrizione-suggerita-che-vincolava-i-medici-di-famiglia\/\">TAR Lazio sentenza n. 11984\/2026: illegittima la &#8220;prescrizione suggerita&#8221; che vincolava i medici di famiglia<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;avv. Beatrice Lucarelli, legale di #SnamiRoma e #SnamiLazio, ci ha segnalato ed analizzato una&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/05\/23\/maternita-e-stabilizzazione-la-corte-costituzionale-n-76-2026-retrodata-il-diploma-mmg-per-la-trasformazione-dellincarico\/\">Maternit\u00e0 e stabilizzazione: la Corte Costituzionale (n.76\/2026) retrodata il diploma MMG per la trasformazione dell&#8217;incarico<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;avv. Beatrice Lucarelli, legale di #SnamiRoma e #SnamiLazio, ci ha segnalato ed analizzato questa&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/05\/19\/trattenimento-in-servizio-oltre-i-70-anni-istruzioni-della-regione-lazio-risalenti-al-27-09-2024\/\">Trattenimento in servizio oltre i 70 anni: istruzioni della Regione Lazio (risalenti al 27\/09\/2024)<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">La nota del 27\/09\/2024 chiarisce che il mantenimento in servizio oltre il limite dei&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/04\/10\/pss-e-fse-2-0-la-proposta-snami-per-togliere-il-carico-burocratico-ai-mmg\/\">PSS e FSE 2.0: la proposta SNAMI per togliere il carico burocratico ai MMG<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">#SNAMI sottolinea che il Profilo #Sanitario Sintetico (#PSS) \u00e8 cruciale per il nuovo Fascicolo&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/04\/03\/%f0%9f%90%a3-buone-festivita-pasquali-da-snamiroma\/\">\ud83d\udc23 Buone Festivit\u00e0 Pasquali da #SNAMIROMA<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">Cari colleghi, in occasione della #Pasqua vi rivolgiamo un caloroso augurio di serenit\u00e0, speranza&hellip;<\/div><\/li>\n<\/ul>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quo usque tandem\u2026 Attoniti veniamo investiti dell\u2019ennesimo piano terapeutico, questa volta cartaceo, per la prescrizione di farmaci a base di acido bempedoico. Mentre ogni giorno ascoltiamo dai decisori promesse di riduzione della burocrazia per il MMG, l\u2019AIFA introduce questo nuovo piano terapeutico. Ormai puntuale come la notte che segue il giorno arrivano con cadenza poco&hellip;<\/p>\n","protected":false},"author":1,"featured_media":681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60,106,21,55,15,56,18,743,69,891,70,57,30,92,3,13,62,14,746,87],"tags":[905,132,128,860,543,341,101,208,74],"class_list":["post-3202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aifa","category-appropriatezza-prescrittiva","category-assistenza-cure-primarie","category-assistenza-primaria","category-comunicazioni-iscritti","category-continuita-assistenziale","category-documenti","category-editoriali","category-frosinone","category-iniziative","category-latina","category-medicina-dei-servizi","category-ministero-della-salute","category-modulistica","category-news","category-regione-e-asl","category-regione-lazio-dispositivi-e-circolari","category-sezioni-provinciali","category-snamilazio","category-unita-cure-primarie","tag-acido-bempedoico","tag-aifa","tag-appropriatezza-prescrittiva","tag-burocrazia","tag-ipercolesterolemia","tag-medici-di-famiglia","tag-mmg","tag-piani-terapeutici","tag-regione"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pb3IKS-PE","jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2020\/01\/aifa_logo.png?fit=662%2C246&ssl=1","_links":{"self":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/3202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/comments?post=3202"}],"version-history":[{"count":1,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/3202\/revisions"}],"predecessor-version":[{"id":3205,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/3202\/revisions\/3205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/media\/681"}],"wp:attachment":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/media?parent=3202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/categories?post=3202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/tags?post=3202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}