{"id":2266,"date":"2021-11-19T12:26:34","date_gmt":"2021-11-19T11:26:34","guid":{"rendered":"https:\/\/www.snamiroma.org\/wp1\/?p=2266"},"modified":"2021-11-19T12:27:49","modified_gmt":"2021-11-19T11:27:49","slug":"somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59","status":"publish","type":"post","link":"https:\/\/www.snamiroma.org\/wp1\/2021\/11\/19\/somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59\/","title":{"rendered":"Somministrazione della dose booster in favore delle fasce di eta 40-59"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">In allegato la comunicazione ufficiale del commissario straordinario all&#8217;emergenza COVID19, Gen. Francesco Paolo Figliuolo, relativa alla somministrazione della dose di richiamo (in inglese denominata &#8220;Booster&#8221;) a favore delle fasce di et\u00e0 40-59 anni, per le vaccinazioni AntiCovid con formulazione basata su mRNA. Con la preghiera di darne massima diffusione presso tutti i colleghi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Documenti allegati:<\/h2>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2021\/11\/949888_19_11_2021_Somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:800px\" aria-label=\"Incorporamento di Incorporamento di 949888_19_11_2021_Somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59-1..\"><\/object><a href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2021\/11\/949888_19_11_2021_Somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59-1.pdf\">949888_19_11_2021_Somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59-1<\/a><a href=\"https:\/\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2021\/11\/949888_19_11_2021_Somministrazione-della-dose-booster-in-favore-delle-fasce-di-eta-40-59-1.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 has-author wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/07\/dott_giuseppe_di_donna.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/07\/26\/in-memoriam-dott-giuseppe-di-donna\/\">IN MEMORIAM: Dott. Giuseppe Di Donna<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">In Memoriam | Oggi apprendiamo della perdita del nostro amato amico e collega, Giuseppe&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/07\/07\/tar-lazio-sentenza-n-11984-2026-illegittima-la-prescrizione-suggerita-che-vincolava-i-medici-di-famiglia\/\">TAR Lazio sentenza n. 11984\/2026: illegittima la &#8220;prescrizione suggerita&#8221; che vincolava i medici di famiglia<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;avv. Beatrice Lucarelli, legale di #SnamiRoma e #SnamiLazio, ci ha segnalato ed analizzato una&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/8582393433309433.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/05\/23\/maternita-e-stabilizzazione-la-corte-costituzionale-n-76-2026-retrodata-il-diploma-mmg-per-la-trasformazione-dellincarico\/\">Maternit\u00e0 e stabilizzazione: la Corte Costituzionale (n.76\/2026) retrodata il diploma MMG per la trasformazione dell&#8217;incarico<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;avv. Beatrice Lucarelli, legale di #SnamiRoma e #SnamiLazio, ci ha segnalato ed analizzato questa&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/05\/immagine.png?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/05\/19\/trattenimento-in-servizio-oltre-i-70-anni-istruzioni-della-regione-lazio-risalenti-al-27-09-2024\/\">Trattenimento in servizio oltre i 70 anni: istruzioni della Regione Lazio (risalenti al 27\/09\/2024)<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">La nota del 27\/09\/2024 chiarisce che il mantenimento in servizio oltre il limite dei&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/4589348598.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/04\/10\/pss-e-fse-2-0-la-proposta-snami-per-togliere-il-carico-burocratico-ai-mmg\/\">PSS e FSE 2.0: la proposta SNAMI per togliere il carico burocratico ai MMG<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">#SNAMI sottolinea che il Profilo #Sanitario Sintetico (#PSS) \u00e8 cruciale per il nuovo Fascicolo&hellip;<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2026\/04\/398549359348.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.snamiroma.org\/wp1\/2026\/04\/03\/%f0%9f%90%a3-buone-festivita-pasquali-da-snamiroma\/\">\ud83d\udc23 Buone Festivit\u00e0 Pasquali da #SNAMIROMA<\/a><div class=\"wp-block-latest-posts__post-author\">di SNAMI Roma<\/div><div class=\"wp-block-latest-posts__post-excerpt\">Cari colleghi, in occasione della #Pasqua vi rivolgiamo un caloroso augurio di serenit\u00e0, speranza&hellip;<\/div><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>In allegato la comunicazione ufficiale del commissario straordinario all&#8217;emergenza COVID19, Gen. Francesco Paolo Figliuolo, relativa alla somministrazione della dose di richiamo (in inglese denominata &#8220;Booster&#8221;) a favore delle fasce di et\u00e0 40-59 anni, per le vaccinazioni AntiCovid con formulazione basata su mRNA. Con la preghiera di darne massima diffusione presso tutti i colleghi. Documenti allegati:<\/p>\n","protected":false},"author":1,"featured_media":2269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[59,60,106,21,55,15,56,400,18,57,29,3,13,62,14,87,399],"tags":[539,549,346,548,313,518],"class_list":["post-2266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accordi-regionali","category-aifa","category-appropriatezza-prescrittiva","category-assistenza-cure-primarie","category-assistenza-primaria","category-comunicazioni-iscritti","category-continuita-assistenziale","category-covid-19","category-documenti","category-medicina-dei-servizi","category-medicina-e-innovazione","category-news","category-regione-e-asl","category-regione-lazio-dispositivi-e-circolari","category-sezioni-provinciali","category-unita-cure-primarie","category-vaccinazione-covid-19","tag-booster","tag-commissario-straordinario-covid","tag-covid19","tag-figliuolo","tag-sars-cov-2","tag-terza-dose"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pb3IKS-Ay","jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.snamiroma.org\/wp1\/wp-content\/uploads\/2021\/11\/pexels-photo-3985170.jpeg?fit=1880%2C1253&ssl=1","_links":{"self":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/2266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/comments?post=2266"}],"version-history":[{"count":3,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/2266\/revisions"}],"predecessor-version":[{"id":2272,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/posts\/2266\/revisions\/2272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/media\/2269"}],"wp:attachment":[{"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/media?parent=2266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/categories?post=2266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snamiroma.org\/wp1\/wp-json\/wp\/v2\/tags?post=2266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}